{"id":9094,"date":"2021-08-01T16:27:07","date_gmt":"2021-08-01T16:27:07","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/?p=9094"},"modified":"2021-08-01T18:52:13","modified_gmt":"2021-08-01T18:52:13","slug":"pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur","title":{"rendered":"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/tchad\">Tchad<\/a>. <\/strong><\/span> <b>Shinichi Sakamoto, 57 ans, travaille pour Shimizu, l&rsquo;une des plus grandes entreprises de construction du Japon. Il fait partie d&rsquo;une main-d&rsquo;\u0153uvre vieillissante et en d\u00e9clin.<\/b><\/p>\n<p>\u00ab\u00a0Le fait est que les statistiques montrent qu&rsquo;un tiers des ouvriers [de la construction japonaise] ont plus de 54 ans et qu&rsquo;ils envisagent de prendre leur retraite si t\u00f4t \u00ab\u00a0, d\u00e9clare M. Sakamoto, qui est chef adjoint de la division de la technologie de production \u00e0 Shimizu.<\/p>\n<p>Et ils ne sont pas remplac\u00e9s par de jeunes agents de construction. \u00ab\u00a0Le nombre de travailleurs de moins de 30 ans est l\u00e9g\u00e8rement sup\u00e9rieur \u00e0 10 %,\u00a0\u00bb dit-il.<\/p>\n<p>En septembre, l&rsquo;entreprise de M. Sakamoto s&rsquo;est dot\u00e9e d&rsquo;un nouveau collaborateur prometteur, un robot.<\/p>\n<p>Robo-Carrier travaille actuellement \u00e0 la construction d&rsquo;une tour d&rsquo;habitation \u00e0 Osaka et transporte chaque nuit de lourdes palettes de plaques de pl\u00e2tre du rez-de-chauss\u00e9e \u00e0 l&rsquo;endroit o\u00f9 elles sont n\u00e9cessaires.<\/p>\n<p>\u00ab\u00a0Pouvez-vous imaginer que les mat\u00e9riaux sont dans la bonne position le matin lorsque les ouvriers viennent sur le chantier ? \u00ab\u00a0Il travaille m\u00eame la nuit.\u00a0\u00bb<\/p>\n<p>La robotique est l&rsquo;un des domaines susceptibles de b\u00e9n\u00e9ficier des r\u00e9seaux mobiles 5G ultrarapides \u00e0 venir. Une meilleure connectivit\u00e9 facilitera la coop\u00e9ration entre plusieurs robots.<\/p>\n<p>De nombreux petits robots pourraient voir le jour, travaillant ensemble sur diff\u00e9rentes parties d&rsquo;une m\u00eame t\u00e2che. C&rsquo;est le cas, par exemple, des robots d&rsquo;impression 3D en cours de d\u00e9veloppement \u00e0 l&rsquo;Universit\u00e9 technologique de Nanyang, \u00e0 Singapour, dont chacun peut imprimer du b\u00e9ton \u00e0 partir d&rsquo;une carte informatique.<\/p>\n<p>Shimizu nous pr\u00e9sente aussi d&rsquo;autres roboticiens.<\/p>\n<p>Robo-Welder soude les colonnes en acier, tandis que Robo-Buddy ins\u00e8re les boulons de suspension et installe les panneaux de plafond.<\/p>\n<p>Les robots fonctionnent de mani\u00e8re autonome, ex\u00e9cutant des t\u00e2ches qu&rsquo;un superviseur leur assigne sur une tablette.<\/p>\n<p>Robo-Carrier peut reconna\u00eetre et \u00e9viter les obstacles, tandis que Robo-Welder utilise la mesure de forme au laser pour d\u00e9terminer les contours de l&rsquo;objet \u00e0 souder.<\/p>\n<p>\u00ab\u00a0Il doit y avoir de plus en plus de robots sur le site \u00ab\u00a0, dit M. Sakamoto. \u00ab\u00a0La p\u00e9nurie de main-d&rsquo;\u0153uvre est notre probl\u00e8me national.\u00a0\u00bb<\/p>\n<p>Le bassin de main-d&rsquo;\u0153uvre dans le secteur de la construction au Japon tombera \u00e0 2,2 millions d&rsquo;ici 2025, contre 3,4 millions en 2014, selon M. Shimizu.<\/p>\n<p>Et ce n&rsquo;est pas seulement un probl\u00e8me pour le Japon. Dans le monde entier \u00e9galement, le secteur de la construction se tourne de plus en plus vers les robots face \u00e0 une main-d&rsquo;\u0153uvre de plus en plus r\u00e9duite et vieillissante.<\/p>\n<p>Globalement, le march\u00e9 mondial des robots de construction va plus que doubler en taille pour atteindre 420 millions de dollars en 2025, contre 200 millions de dollars en 2017, selon les consultants de QY Research.<\/p>\n<p>Aux \u00c9tats-Unis, les travailleurs de la construction vieillissent \u00e9galement. La moyenne d&rsquo;\u00e2ge est actuellement de 43 ans, affirme Jeremy Searock, cofondateur de la soci\u00e9t\u00e9 Advanced Construction Robotics de Pittsburgh.<\/p>\n<p>Il y a dix ans, la moyenne d&rsquo;\u00e2ge \u00e9tait d&rsquo;environ 30 ans.<\/p>\n<p>Et 80 % des entrepreneurs g\u00e9n\u00e9raux am\u00e9ricains disent qu&rsquo;ils ont du mal \u00e0 pourvoir les postes vacants de travailleurs qualifi\u00e9s, selon une enqu\u00eate r\u00e9alis\u00e9e en ao\u00fbt.<\/p>\n<p>Il y a une \u00ab\u00a0tendance claire\u00a0\u00bb, dit M. Searock, \u00ab\u00a0les jeunes g\u00e9n\u00e9rations ne se lancent plus dans le secteur de la construction\u00a0\u00bb.<\/p>\n<p>C&rsquo;est pourquoi Shimizu a investi 20 milliards de yens (140 millions de livres sterling ; 179 millions de dollars US) depuis 2015 pour d\u00e9velopper des robots de construction, explique Hideo Imamura. Ses robots r\u00e9duisent les besoins en main-d&rsquo;\u0153uvre pour une t\u00e2che donn\u00e9e de 70 \u00e0 80 %, dit-il.<\/p>\n<p>Aux \u00c9tats-Unis, pr\u00e8s de la moiti\u00e9 des emplois dans la construction pourraient \u00eatre remplac\u00e9s par des robots d&rsquo;ici 2057, selon des chercheurs de l&rsquo;Universit\u00e9 de l&rsquo;Illinois \u00e0 Urbana-Champaign et du Midwest Economic Policy Institute.<\/p>\n<p>En plus d&rsquo;\u00eatre infatigables, les robots peuvent effectuer les travaux les plus difficiles et les plus dangereux sur un chantier de construction, dit M. Sakamoto, \u00e9vitant potentiellement des blessures et des pertes de vie.<\/p>\n<p>\u00ab\u00a0Le travail qui convient aux robots est pour les robots, et le travail qui convient aux humains est pour les humains \u00ab\u00a0, explique-t-il.<\/p>\n<p>A l&rsquo;avenir, gr\u00e2ce \u00e0 la 5G associ\u00e9e au temps de latence plus faible &#8211; l&rsquo;intervalle de temps entre une demande et une r\u00e9ponse &#8211; les robots seront en mesure de r\u00e9aliser plus de t\u00e2ches.<\/p>\n<p>Le r\u00e9sultat final est un robot moins cher et plus intelligent.<\/p>\n<p>Shimizu contr\u00f4le actuellement ses robots en 4G mobile et wi-fi, ce qui signifie que lorsqu&rsquo;ils travaillent sur des b\u00e2timents de plus de 200m de haut, ils doivent \u00e9tendre la zone du r\u00e9seau wi-fi en utilisant des relais.<\/p>\n<p>La 5G leur permettrait de se lib\u00e9rer de cette d\u00e9pendance, selon l&rsquo;entreprise.<\/p>\n<p>Les robots pourraient alors effectuer des t\u00e2ches dangereuses ou r\u00e9p\u00e9titives sur des sites distants sans avoir besoin d&rsquo;installer une station de base wi-fi &#8211; \u00e0 condition, bien s\u00fbr, que le r\u00e9seau 5G couvre les sites concern\u00e9s.<\/p>\n<p>L&rsquo;un des \u00e9l\u00e9ments les plus durs de la construction de ponts consiste \u00e0 attacher ensemble des barres d&rsquo;armature &#8211; les barres d&rsquo;acier d&rsquo;armature qui ajoutent de la r\u00e9sistance \u00e0 la traction au b\u00e9ton.<\/p>\n<p>\u00ab\u00a0Se pencher sur un pont, sous le soleil chaud, en manipulant avec les mains ces ouvrages, c&rsquo;est un travail difficile \u00ab\u00a0, dit M. Searock.<\/p>\n<p>Il pourrait y avoir des centaines de milliers, voire des millions de points de jointure \u00e0 lier.<\/p>\n<p>Et dans le Nord-Est des \u00c9tats-Unis, dit-il, il y a une \u00ab\u00a0p\u00e9nurie prononc\u00e9e\u00a0\u00bb de main-d&rsquo;\u0153uvre pour ce travail, accentu\u00e9e par le caract\u00e8re saisonnier de ce dernier.<\/p>\n<p>Ainsi, l&rsquo;ann\u00e9e derni\u00e8re, Advanced Construction Robotics a d\u00e9velopp\u00e9 un robot &#8211; TyBot &#8211; pour faire ce travail, en travaillant sur le pont de Freedom Road dans le comt\u00e9 de Beaver, en Pennsylvanie.<\/p>\n<p>Il a \u00e9gal\u00e9 24 000 intersections de barres d&rsquo;armature \u00e0 un rythme de 5,5 secondes pour chacune d&rsquo;elles. Le cinqui\u00e8me TyBot sort maintenant de la cha\u00eene de montage, dit M. Searock.<\/p>\n<p>Entre-temps, l&rsquo;Institut national des sciences et technologies industrielles avanc\u00e9es de Tokyo a construit un prototype de robot, appel\u00e9 HRP-5P, qui peut installer des cloisons en plaques de pl\u00e2tre.<\/p>\n<p>Et l&rsquo;entreprise new-yorkaise Construction Robotics a r\u00e9cemment construit un ma\u00e7on semi-automatique &#8211; SAM en abr\u00e9g\u00e9 &#8211; qui a pos\u00e9 250 000 briques pour le Poff Federal Building \u00e0 Roanoke, Virginie.<\/p>\n<p>Avec 380 briques pos\u00e9es \u00e0 l&rsquo;heure, c&rsquo;est six fois plus rapide qu&rsquo;un ma\u00e7on humain, disent ses fabricants.<\/p>\n<p>L&rsquo;industrie mondiale de la construction a pris du retard par rapport \u00e0 d&rsquo;autres secteurs en mati\u00e8re d&rsquo;investissement technologique, en grande partie parce qu&rsquo;elle est \u00ab\u00a0notoirement fragment\u00e9e\u00a0\u00bb, d\u00e9clare Will Hughes, professeur de gestion et d&rsquo;\u00e9conomie de la construction \u00e0 l&rsquo;Universit\u00e9 de Reading.<\/p>\n<p>Cette nature fragment\u00e9e signifie que de nombreuses petites entreprises sont \u00ab\u00a0d\u00e9pendantes du statu quo\u00a0\u00bb, de sorte que \u00ab\u00a0les pratiques de travail remontent \u00e0 l&rsquo;\u00e9poque victorienne\u00a0\u00bb, dit-il.<\/p>\n<p>Mais les paralysantes p\u00e9nuries de main-d&rsquo;\u0153uvre laissent penser que les premi\u00e8res entreprises de construction qui mettront les robots au travail de mani\u00e8re efficace auront un avantage significatif, affirme-t-il.<\/p>\n<p>Alors ne vous inqui\u00e9tez pas si dans quelques ann\u00e9es vous ouvrez votre porte et voyez un robot Dalek.<\/p>\n<p>Il peut \u00eatre l\u00e0 pour convertir votre vous rendre un service de construction.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. Shinichi Sakamoto, 57 ans, travaille pour Shimizu, l&rsquo;une des plus grandes entreprises de construction du Japon. Il fait partie d&rsquo;une main-d&rsquo;\u0153uvre vieillissante et en d\u00e9clin. \u00ab\u00a0Le fait est que les statistiques montrent qu&rsquo;un tiers des ouvriers [de la construction japonaise] ont plus de 54 ans et qu&rsquo;ils envisagent de prendre leur retraite [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":9093,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[37,292,1136,1135,29],"class_list":["post-9094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-tchad","tag-futur","tag-robots","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur - tchad<\/title>\n<meta name=\"description\" content=\"Shinichi Sakamoto, 57 ans, travaille pour Shimizu, l&#039;une des plus grandes entreprises de construction du Japon. Il f ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur\" \/>\n<meta property=\"og:description\" content=\"Shinichi Sakamoto, 57 ans, travaille pour Shimizu, l&#039;une des plus grandes entreprises de construction du Japon. Il f ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-01T16:27:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-01T18:52:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur\",\"datePublished\":\"2021-08-01T16:27:07+00:00\",\"dateModified\":\"2021-08-01T18:52:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur\"},\"wordCount\":1266,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Tchad\",\"futur\",\"robots\",\"Tchad\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur\",\"name\":\"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg\",\"datePublished\":\"2021-08-01T16:27:07+00:00\",\"dateModified\":\"2021-08-01T18:52:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Shinichi Sakamoto, 57 ans, travaille pour Shimizu, l'une des plus grandes entreprises de construction du Japon. Il f ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg\",\"width\":720,\"height\":405,\"caption\":\"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur - tchad","description":"Shinichi Sakamoto, 57 ans, travaille pour Shimizu, l'une des plus grandes entreprises de construction du Japon. Il f ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur","og_locale":"fr_FR","og_type":"article","og_title":"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur","og_description":"Shinichi Sakamoto, 57 ans, travaille pour Shimizu, l'une des plus grandes entreprises de construction du Japon. Il f ...","og_url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur","og_site_name":"tchad","article_published_time":"2021-08-01T16:27:07+00:00","article_modified_time":"2021-08-01T18:52:13+00:00","og_image":[{"width":720,"height":405,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur","datePublished":"2021-08-01T16:27:07+00:00","dateModified":"2021-08-01T18:52:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur"},"wordCount":1266,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg","keywords":["Africa Press","Africa Press-Tchad","futur","robots","Tchad"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur","url":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur","name":"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg","datePublished":"2021-08-01T16:27:07+00:00","dateModified":"2021-08-01T18:52:13+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Shinichi Sakamoto, 57 ans, travaille pour Shimizu, l'une des plus grandes entreprises de construction du Japon. Il f ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2021\/08\/img-6106cac7f16be.jpg","width":720,"height":405,"caption":"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/toutes-les-actualites\/pourquoi-les-robots-remplaceront-les-ouvriers-sur-les-chantiers-du-futur#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Pourquoi les robots remplaceront les ouvriers sur les chantiers du futur"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/9094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=9094"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/9094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/9093"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=9094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=9094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=9094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}