{"id":97767,"date":"2025-12-23T11:44:00","date_gmt":"2025-12-23T11:44:00","guid":{"rendered":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain"},"modified":"2025-12-23T12:02:24","modified_gmt":"2025-12-23T12:02:24","slug":"lavrov-securite-essentielle-au-developpement-africain","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain","title":{"rendered":"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Tchad. <\/strong><\/span>L&rsquo;Afrique se r\u00e9veille apr\u00e8s l&rsquo;\u00e8re coloniale, d\u00e9clare le ministre des Affaires \u00e9trang\u00e8res Sergue\u00ef Lavrov lors de la 2\u1d49 Conf\u00e9rence minist\u00e9rielle du Forum de partenariat Russie-Afrique au Caire<br \/>\nLe ministre russe des Affaires e\u0301trange\u0300res, Serguei\u0308 Lavrov, a de\u0301clare\u0301 samedi que le renforcement de la paix et de la se\u0301curite\u0301 en Afrique e\u0301tait une condition essentielle pour assurer le de\u0301veloppement progressif et durable du continent et un e\u0301le\u0301ment important pour maintenir la stabilite\u0301 mondiale.<\/p>\n<p>S&rsquo;exprimant lors de la deuxie\u0300me confe\u0301rence ministe\u0301rielle du Forum de partenariat Russie-Afrique au Caire, la capitale e\u0301gyptienne, Lavrov a souligne\u0301 l&rsquo;engagement de la Russie a\u0300 soutenir les pays africains a\u0300 cet e\u0301gard.<\/p>\n<p>\u00ab Nous accordons une grande importance aux questions relatives au renforcement de la paix et de la se\u0301curite\u0301 sur le continent africain. Il s&rsquo;agit d&rsquo;une condition essentielle pour garantir un de\u0301veloppement socio-e\u0301conomique progressif et durable et d&rsquo;un e\u0301le\u0301ment important pour le maintien de la stabilite\u0301 mondiale \u00bb, a-t-il de\u0301clare\u0301.<\/p>\n<p>Lavrov a note\u0301 que Moscou fournissait une assistance aux pays africains pour le de\u0301minage et la neutralisation des engins explosifs improvise\u0301s, et qu&rsquo;elle de\u0301veloppait des programmes de formation professionnelle destine\u0301s au personnel militaire et aux forces de l&rsquo;ordre.<\/p>\n<p>\u00ab Nous pensons qu&rsquo;il est important de traduire en termes pratiques la de\u0301cision prise lors du deuxie\u0300me sommet Russie-Afrique d&rsquo;e\u0301tablir un me\u0301canisme permanent de dialogue russo-africain au plus haut niveau afin de coordonner tous les efforts dans le domaine de la se\u0301curite\u0301 \u00bb, a-t-il ajoute\u0301.<\/p>\n<p>Le haut diplomate russe a souligne\u0301 que la re\u0301solution durable des conflits en Afrique passe par la prise en compte de leurs causes profondes, \u00ab qui trouvent leur origine dans l&rsquo;he\u0301ritage du colonialisme occidental \u00bb.<\/p>\n<p>Il a critique\u0301 le syste\u0300me colonial pour avoir \u00ab viole\u0301 la trajectoire historique naturelle des peuples africains, trace\u0301 arbitrairement des frontie\u0300res et e\u0301tabli un ordre e\u0301conomique oriente\u0301 vers les inte\u0301re\u0302ts des me\u0301tropoles occidentales \u00bb. \u00ab<\/p>\n<p>Malheureusement, diverses formes de ne\u0301ocolonialisme persistent encore aujourd&rsquo;hui. Nous sommes pre\u0302ts a\u0300 agir de concert avec nos partenaires africains pour les e\u0301radiquer, notamment en e\u0301laborant des instruments juridiques permettant d&rsquo;e\u0301valuer et d&rsquo;indemniser les dommages cause\u0301s pendant la pe\u0301riode coloniale \u00bb, a de\u0301clare\u0301 Lavrov.<\/p>\n<p>Selon lui, le monde assiste au \u00ab deuxie\u0300me re\u0301veil \u00bb de l&rsquo;Afrique et a\u0300 la consolidation de son autorite\u0301 internationale.<\/p>\n<p>Le ministre des Affaires e\u0301trange\u0300res a e\u0301galement souligne\u0301 la croissance du commerce bilate\u0301ral, notant que la coope\u0301ration e\u0301conomique se renforce.<\/p>\n<p>\u00ab L&rsquo;anne\u0301e dernie\u0300re, le chiffre d&rsquo;affaires commercial a augmente\u0301 de 13 %, atteignant 28 milliards de dollars. Je suis convaincu que cela est loin d&rsquo;e\u0302tre une limite. Nous sommes de\u0301termine\u0301s a\u0300 continuer a\u0300 exploiter le vaste potentiel de notre coope\u0301ration pratique \u00bb, a-t-il conclu.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <span style=\"color: #ff6600\">Tchad<\/span>, suivez <span style=\"color: #ff6600\">Africa-Press<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Tchad. L&rsquo;Afrique se r\u00e9veille apr\u00e8s l&rsquo;\u00e8re coloniale, d\u00e9clare le ministre des Affaires \u00e9trang\u00e8res Sergue\u00ef Lavrov lors de la 2\u1d49 Conf\u00e9rence minist\u00e9rielle du Forum de partenariat Russie-Afrique au Caire Le ministre russe des Affaires e\u0301trange\u0300res, Serguei\u0308 Lavrov, a de\u0301clare\u0301 samedi que le renforcement de la paix et de la se\u0301curite\u0301 en Afrique e\u0301tait une [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":97766,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[342,3430,4068,29],"class_list":["post-97767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","category-toutes-les-actualites","tag-afrique","tag-russie-afrique","tag-serguei-lavrov","tag-tchad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain - tchad<\/title>\n<meta name=\"description\" content=\"\u0301veille apre\u0300s l&#039;e\u0300re coloniale, de\u0301clare le ministre des Affaires e\u0301trange\u0300res Serguei\u0308 Lavrov lors de la 2e Co ... ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain\" \/>\n<meta property=\"og:description\" content=\"\u0301veille apre\u0300s l&#039;e\u0300re coloniale, de\u0301clare le ministre des Affaires e\u0301trange\u0300res Serguei\u0308 Lavrov lors de la 2e Co ... ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain\" \/>\n<meta property=\"og:site_name\" content=\"tchad\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-23T11:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-23T12:02:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain\",\"datePublished\":\"2025-12-23T11:44:00+00:00\",\"dateModified\":\"2025-12-23T12:02:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain\"},\"wordCount\":522,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg\",\"keywords\":[\"Afrique\",\"Russie-Afrique\",\"Sergue\u00ef Lavrov\",\"Tchad\"],\"articleSection\":[\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain\",\"name\":\"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain - tchad\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg\",\"datePublished\":\"2025-12-23T11:44:00+00:00\",\"dateModified\":\"2025-12-23T12:02:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"\u0301veille apre\u0300s l'e\u0300re coloniale, de\u0301clare le ministre des Affaires e\u0301trange\u0300res Serguei\u0308 Lavrov lors de la 2e Co ... ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg\",\"width\":864,\"height\":486,\"caption\":\"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/tchad\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#website\",\"url\":\"https:\/\/www.africa-press.net\/tchad\/\",\"name\":\"tchad\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain - tchad","description":"\u0301veille apre\u0300s l'e\u0300re coloniale, de\u0301clare le ministre des Affaires e\u0301trange\u0300res Serguei\u0308 Lavrov lors de la 2e Co ... ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain","og_locale":"fr_FR","og_type":"article","og_title":"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain","og_description":"\u0301veille apre\u0300s l'e\u0300re coloniale, de\u0301clare le ministre des Affaires e\u0301trange\u0300res Serguei\u0308 Lavrov lors de la 2e Co ... ...","og_url":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain","og_site_name":"tchad","article_published_time":"2025-12-23T11:44:00+00:00","article_modified_time":"2025-12-23T12:02:24+00:00","og_image":[{"width":864,"height":486,"url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain","datePublished":"2025-12-23T11:44:00+00:00","dateModified":"2025-12-23T12:02:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain"},"wordCount":522,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg","keywords":["Afrique","Russie-Afrique","Sergue\u00ef Lavrov","Tchad"],"articleSection":["Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain","url":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain","name":"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain - tchad","isPartOf":{"@id":"https:\/\/www.africa-press.net\/tchad\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg","datePublished":"2025-12-23T11:44:00+00:00","dateModified":"2025-12-23T12:02:24+00:00","author":{"@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"\u0301veille apre\u0300s l'e\u0300re coloniale, de\u0301clare le ministre des Affaires e\u0301trange\u0300res Serguei\u0308 Lavrov lors de la 2e Co ... ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#primaryimage","url":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg","contentUrl":"https:\/\/static.africa-press.net\/tchad\/sites\/41\/2025\/12\/sm_1766478729.291048.jpg","width":864,"height":486,"caption":"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/tchad\/politique\/lavrov-securite-essentielle-au-developpement-africain#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/tchad\/"},{"@type":"ListItem","position":2,"name":"Lavrov: Se\u0301curite\u0301 Essentielle au De\u0301veloppement Africain"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/tchad\/#website","url":"https:\/\/www.africa-press.net\/tchad\/","name":"tchad","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/tchad\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/tchad\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/97767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/comments?post=97767"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/posts\/97767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media\/97766"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/media?parent=97767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/categories?post=97767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/tchad\/wp-json\/wp\/v2\/tags?post=97767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}