{"id":1648,"date":"2021-11-11T16:58:58","date_gmt":"2021-11-11T16:58:58","guid":{"rendered":"https:\/\/www.africa-press.net\/togo\/?p=1648"},"modified":"2021-11-11T14:03:13","modified_gmt":"2021-11-11T14:03:13","slug":"togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra","title":{"rendered":"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Togo. <\/strong><\/span><b>Peuple togolais que nous sommes, ne perdons jamais d\u00b4espoir pour notre pays et son unification. C\u00b4est un pays qui souffre et cette souffrance vient de nous-m\u00eames et de notre \u00e9go\u00efsme mais il se rel\u00e8vera un jour et sera uni. Togo britannique nous reviendra un jour, quel que soit le temps que cela prendra. Tout est possible. Seule notre unit\u00e9 et l\u00b4amour pour notre pays compteront pour atteindre cet objectif.<\/b><\/p>\n<p>En venant au monde chacun a une mission bien pr\u00e9cise sur cette terre qui lui a \u00e9t\u00e9 assign\u00e9e, quelle que soit sa dur\u00e9e d\u00b4existence ou de vie. La mienne c\u00b4est de me battre politiquement pour l\u00b4unification du pays qui m\u00b4a vu na\u00eetre. Moi, je ne suis pas venu au monde pour chercher de l\u00b4argent. Je suis venu au monde pour aimer mon pays et lutter pour lui. Non seulement c\u00b4est mon engagement mais aussi c\u00b4est mon devoir. On ne fuit pas son devoir. Quelle que soit sa nature et sa taille, je ne fuirai pas la mienne. Togo britannique, nous l\u00b4aurons un jour. M\u00eame si ce ne sera pas de mon vivant, la base sera pos\u00e9e. La bataille juridique et diplomatique sera difficile mais nous allons la gagner face au Ghana.<\/p>\n<p>Mais seul, je ne peux rien car une seule personne ne peut pas mener le combat de tout un pays et le gagner, moins encore celui de l\u00b4unification de notre pays. Pour cela il faut notre unit\u00e9, du nord au sud derri\u00e8re ce combat. M\u00eame si nous, nous ne pouvons pas voir ce r\u00eave se r\u00e9aliser de notre vivant, au moins il faut poser les bases et les jalons pour les prochaines g\u00e9n\u00e9rations qui r\u00e9cup\u00e9reront de droit cette partie de notre territoire. Mon optimisme pour la r\u00e9unification des deux Togos vient des exemples.<\/p>\n<p>130 ans d\u00b4absence, 26 \u0153uvres d\u00b4art pill\u00e9es au B\u00e9nin par la France dans la bataille de colonisation, retrouvent leur terre natale ce jour du 10 novembre 2021 car le pr\u00e9sident Patrice Talon l\u00b4a voulu et l\u00b4a formellement demand\u00e9 avec insistance aupr\u00e8s des autorit\u00e9s fran\u00e7aises. Je suis confiant pour notre unification aussi car j\u00b4ai cette force qui m\u00b4anime et qui anime aussi sans doute d\u00b4autres Togolais comme moi et que je ne connais pas mais qui auraient le m\u00eame souhait ardent et la m\u00eame force patriotique que moi pour r\u00e9cup\u00e9rer le Togo britannique. Le moment venu, je pense que nous m\u00e8nerons ensemble ce combat d\u00b4unification pour notre pays et pour sa grandeur. La r\u00e9unification allemande \u00e9tait possible car les Allemands l\u00b4ont voulue et ils aiment leur pays. Le temps aussi a chang\u00e9 en leur faveur en 1989 pour la permettre avec la chute du mur de Berlin. Pourquoi pas chez nous au Togo m\u00eame si ce n\u00b4\u00e9tait pas un mur qui est \u00e9rig\u00e9 au Togo. Un jour, ce temps aussi d\u00b4unification arrivera au Togo en notre faveur. Nous allons nous battre et montrer notre d\u00e9termination en prouvant avec les documents \u00e0 l\u00b4appui que ce r\u00e9f\u00e9rendum du 9 mai 1956 est du faux et que tout est organis\u00e9 dans la seule intention de rattacher cette partie du Togo au Ghana d\u00b4aujourd\u00b4hui. J\u00b4ai tous les documents de l\u00b4ONU, fiables \u00e0 prouver pour mener ce combat.<\/p>\n<p>Aujourd\u00b4hui nous sommes en 2021. Ce r\u00e9f\u00e9rendum a \u00e9t\u00e9 organis\u00e9 en 1956. Donc, \u00e7a fait 65 ans. Ce temps \u00e9coul\u00e9 n\u00b4est rien. Non, on ne va pas d\u00e9sesp\u00e9rer.<\/p>\n<p>Qui a cru qu\u00b4un jour, 26 \u0153uvres d\u00b4art pill\u00e9es par la France au B\u00e9nin 130 ans apr\u00e8s, en 1892 au moment de la bataille de la colonisation, allaient retrouver la terre natale ? Personne ne l\u00b4aurait cru, m\u00eame les B\u00e9ninois eux-m\u00eames ne l\u00b4auraient jamais cru. Et pourtant, apr\u00e8s 130 ans du temps \u00e9coul\u00e9, je dis bien 130 ans, ces oeuvres d\u00b4art retrouvent leur terre natale aujourd\u00b4hui 10 novembre 2021. C\u00b4est un grand jour pour le B\u00e9nin mais aussi pour le Togo car c\u00b4est un pays voisin. C\u00b4est un espoir qui rena\u00eet aussi pour le Togo pour r\u00e9parer les injustices entra\u00eenant le partage du Togo.<\/p>\n<p>Dans la grandeur d\u00b4un pays ou son rayonnement, le pr\u00e9sident joue un grand r\u00f4le. C\u00b4est pourquoi il faut de la chance pour un peuple d\u00b4\u00eatre dirig\u00e9 par les pr\u00e9sidents patriotes. C\u00b4est Patrice Talon qui a formul\u00e9 cette demande avec s\u00e9rieux et d\u00e9termination en exigeant le retour des \u0153uvres d\u00b4art b\u00e9ninoises, pill\u00e9es par la France pendant la bataille colonisatrice en 1892. Il l\u00b4a fait au temps de Fran\u00e7ois Hollande, pr\u00e9sident de la r\u00e9publique fran\u00e7aise mais ce dernier a rejet\u00e9 sa demande. Mais il n\u00b4a pas baiss\u00e9 les bras. Un jour aussi viendra o\u00f9 un pr\u00e9sident togolais, patriote, formulera cette demande de la r\u00e9cup\u00e9ration de notre territoire \u00e0 l\u00b4endroit d\u00b4un pr\u00e9sident ghan\u00e9en.<\/p>\n<p>Convenez avec moi que lorsqu\u00b4on prend quelque chose injustement \u00e0 autrui ou bien on le gagne d\u00b4une mani\u00e8re injuste ou frauduleuse, la conscience de celui qui l\u00b4a pris ou gagn\u00e9 frauduleusement n\u00b4est jamais tranquille. Je suis s\u00fbr et certain que les pr\u00e9sidents successifs du Ghana ne sont jamais aussi tranquilles dans leur conscience. Car ils savent que le Togo britannique a \u00e9t\u00e9 rattach\u00e9 d\u00b4une mani\u00e8re injuste ou frauduleuse \u00e0 base d\u00b4un r\u00e9f\u00e9rendum au Ghana et que ce territoire quittera un jour le Ghana pour revenir au Togo. Ils sont conscients de cela qu\u00b4un pr\u00e9sident togolais, patriotique et nationaliste le revendiquera un jour. C\u00b4est que ce moment n\u00b4est pas encore arriv\u00e9. Je prie Dieu que cet honneur me revienne un jour \u00e0 la hauteur de ma force patriotique et de mon ambition pour faire ce boulot laiss\u00e9 \u00e0 mi-chemin par les p\u00e8res nationalistes et vaillants, auxquels on doit tous les honneurs patriotiques aussi bien aux Togolais nationalistes du Togo britannique que du Togo fran\u00e7ais au temps de leur combat h\u00e9ro\u00efque men\u00e9 ensemble pour l\u00b4unification des deux territoires divis\u00e9s face aux ennemis de la patrie et des tra\u00eetres qui luttaient pour la grandeur de la France au lieu de lutter pour l\u00b4unification et la grandeur du Togo, leur patrie.<\/p>\n<p>Mes chers compatriotes, un jour cette bande de terre du Togo britannique qui longe notre pays au sud jusqu\u00b4au nord \u00e0 Dapaong nous reviendra. J\u00b4ai cette confiance. Mais nous devons aussi savoir que cela ne tombera pas du ciel. Sans notre action, sans notre volont\u00e9 de la r\u00e9cup\u00e9rer, cette partie de terre ne nous reviendra jamais. Si le pr\u00e9sident Patrice Talon n\u00b4avait pas agi, s\u00b4il n\u00b4avait pas formul\u00e9 cette demande patriotique, la France ne remettrait jamais ces oeuvres d\u00b4art, m\u00eame si Emmanuel Macron avait pr\u00e9alablement fait cette d\u00e9claration dans son discours au Burkina Fasso en 2017 et s\u00b4est engag\u00e9 \u00e0 les restituer.<\/p>\n<p>Nous aussi, nous devons agir aupr\u00e8s des autorit\u00e9s ghan\u00e9ennes afin qu\u00b4elles sachent que nous consid\u00e9rons toujours cette partie du Togo comme notre territoire, mais seul un pr\u00e9sident de la r\u00e9publique peut le faire. Nous allons \u00e0 tout prix, prouver que le Royaume-Uni n\u00b4a pas respect\u00e9 son engagement qu\u00b4il a pris aupr\u00e8s de la SDN devenue aujourd\u00b4hui ONU, d\u00b4administrer le Togo plac\u00e9 sous sa tutelle et non de l\u00b4int\u00e9grer dans sa colonie Gold Coast, actuel Ghana pour en faire une seule colonie. Convenez avec moi que le Royaume-Uni est un pays qui ne respecte jamais ses engagements qu\u00b4il a pris. Ils sont comme \u00e7a, les Anglais. Prenons par exemple les engagements qu\u00b4ils ont pris et les accords qu\u00b4ils ont sign\u00e9s en sortant de l\u00b4Union europ\u00e9enne. Aussit\u00f4t leur sortie, le Premier ministre Boris Johnson est en train de les remettre en cause vis-\u00e0-vis de l\u00b4union europ\u00e9enne. C\u00b4est le m\u00eame comportement qu\u00b4ils avaient adopt\u00e9 vis-\u00e0-vis du Togo britannique quand il \u00e9tait sous leur tutelle administrative. Si en 2021 le Royaume-Uni agissait de la sorte vis-\u00e0-vis de l\u00b4UE sans g\u00eane, quelle force aurait la population du Togo britannique en 1956 pour s\u00b4opposer \u00e0 ce r\u00e9f\u00e9rendum pr\u00e9par\u00e9 et organis\u00e9 par le Royaume-Uni, une puissance coloniale de Gold Coast, m\u00eame si le Conseil de tutelle de l\u00b4ONU en \u00e9tait l\u00b4initiatrice ? Qui a \u00e9mis l\u00b4id\u00e9e de ce r\u00e9f\u00e9rendum si ce n\u00b4est pas le gouvernement de Kwame N\u00b4Krumah avec l\u00b4appui de sa puissance coloniale, le Royaume-Uni aupr\u00e8s du Conseil de tutelle de l\u00b4ONU. La bataille sera rude et longue mais nous allons la gagner. Le Togo britannique nous reviendra un jour \u00e0 coup s\u00fbr. C\u00b4est pour nous.<\/p>\n<p>Jamais, ne consid\u00e9rons pas que c\u00b4est fini. Rien n\u00b4est fini. Apr\u00e8s 130 ans les B\u00e9ninois ont retrouv\u00e9 une partie de leurs arts pris injustement. Alors, pourquoi pas nous les Togolais, nous ne pouvons pas retrouver un jour notre territoire, pris injustement et frauduleusement sous une forme l\u00e9gale qui est le r\u00e9f\u00e9rendum ? Certes, le Ghana ne va pas nous le remettre comme un simple courrier dans la bo\u00eete \u00e0 lettre. Ce serait au prix de la bataille juridique et diplomatique pour la gagner, cette cause commune. Et surtout, je dis bien surtout, il faut notre unit\u00e9 au Togo, du sud au nord car c\u00b4est une cause commune. Sans cette unit\u00e9 des Togolais on n\u00b4aura rien. Ce n\u00b4est pas avec cette division d\u00b4aujourd\u00b4hui dans un Togo o\u00f9 un seul parti veut diriger le pays pendant 100 ans et l\u00b4opposition aussi tr\u00e8s divis\u00e9e que nous allons pouvoir r\u00e9cup\u00e9rer le Togo britannique. C\u00b4est un \u00e9chec d\u00b4avance sans notre unit\u00e9 et l\u00b4amour pour le Togo.<\/p>\n<p>Si nous n\u00b4enterrons pas notre \u00e9go\u00efsme et individualisme et surtout aussi le tribalisme, nous ne pouvons jamais faire de ce pays, un pays beau et \u00e9riger sa grandeur qu\u00b4il m\u00e9ritait au temps des Allemands et qui lui a valu le nom de Musterkolonie Togo ( Togo, colonie mod\u00e8le).<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/togo\">Togo<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Togo. Peuple togolais que nous sommes, ne perdons jamais d\u00b4espoir pour notre pays et son unification. C\u00b4est un pays qui souffre et cette souffrance vient de nous-m\u00eames et de notre \u00e9go\u00efsme mais il se rel\u00e8vera un jour et sera uni. Togo britannique nous reviendra un jour, quel que soit le temps que cela [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":1647,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,10],"tags":[36,49,493,492,50,396],"class_list":["post-1648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-togo","tag-dr-christian-spieker","tag-opinion","tag-togo","tag-togo-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d - Togo<\/title>\n<meta name=\"description\" content=\"Peuple togolais que nous sommes, ne perdons jamais d\u00b4espoir pour notre pays et son unification. C\u00b4est un pays qui sou ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d\" \/>\n<meta property=\"og:description\" content=\"Peuple togolais que nous sommes, ne perdons jamais d\u00b4espoir pour notre pays et son unification. C\u00b4est un pays qui sou ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra\" \/>\n<meta property=\"og:site_name\" content=\"Togo\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-11T16:58:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/togo\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d\",\"datePublished\":\"2021-11-11T16:58:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra\"},\"wordCount\":1770,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Togo\",\"Dr Christian Spieker\",\"Opinion\",\"Togo\",\"Togo Actualit\u00e9\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra\",\"url\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra\",\"name\":\"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d - Togo\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/togo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg\",\"datePublished\":\"2021-11-11T16:58:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/togo\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Peuple togolais que nous sommes, ne perdons jamais d\u00b4espoir pour notre pays et son unification. C\u00b4est un pays qui sou ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg\",\"width\":720,\"height\":480,\"caption\":\"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/togo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/togo\/#website\",\"url\":\"https:\/\/www.africa-press.net\/togo\/\",\"name\":\"Togo\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/togo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/togo\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d - Togo","description":"Peuple togolais que nous sommes, ne perdons jamais d\u00b4espoir pour notre pays et son unification. C\u00b4est un pays qui sou ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra","og_locale":"fr_FR","og_type":"article","og_title":"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d","og_description":"Peuple togolais que nous sommes, ne perdons jamais d\u00b4espoir pour notre pays et son unification. C\u00b4est un pays qui sou ...","og_url":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra","og_site_name":"Togo","article_published_time":"2021-11-11T16:58:58+00:00","og_image":[{"width":720,"height":480,"url":"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/togo\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d","datePublished":"2021-11-11T16:58:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra"},"wordCount":1770,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg","keywords":["Africa Press","Africa Press-Togo","Dr Christian Spieker","Opinion","Togo","Togo Actualit\u00e9"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra","url":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra","name":"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d - Togo","isPartOf":{"@id":"https:\/\/www.africa-press.net\/togo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg","datePublished":"2021-11-11T16:58:58+00:00","author":{"@id":"https:\/\/www.africa-press.net\/togo\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Peuple togolais que nous sommes, ne perdons jamais d\u00b4espoir pour notre pays et son unification. C\u00b4est un pays qui sou ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#primaryimage","url":"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg","contentUrl":"https:\/\/static.africa-press.net\/togo\/sites\/58\/2021\/11\/img-618d2283ab6f9.jpg","width":720,"height":480,"caption":"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/togo\/dossiers\/togo-dr-christian-spieker-un-jour-cette-bande-de-terre-du-togo-britanniquenous-reviendra#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/togo\/"},{"@type":"ListItem","position":2,"name":"Togo-Dr Christian Spieker \u201cUn jour cette bande de terre du Togo britannique\u2026nous reviendra\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/togo\/#website","url":"https:\/\/www.africa-press.net\/togo\/","name":"Togo","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/togo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/togo\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/posts\/1648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/comments?post=1648"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/posts\/1648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/media\/1647"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/media?parent=1648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/categories?post=1648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/togo\/wp-json\/wp\/v2\/tags?post=1648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}